{"id":43118,"date":"2025-07-08T07:39:24","date_gmt":"2025-07-08T05:39:24","guid":{"rendered":"https:\/\/www.incliva.es\/vi-edicion-del-concurso-de-ideas-innovadoras-del-departamento-clinico-malvarrosa\/"},"modified":"2025-07-08T12:14:09","modified_gmt":"2025-07-08T10:14:09","slug":"vi-edicion-del-concurso-de-ideas-innovadoras-del-departamento-clinico-malvarrosa","status":"publish","type":"post","link":"https:\/\/www.incliva.es\/en\/vi-edicion-del-concurso-de-ideas-innovadoras-del-departamento-clinico-malvarrosa\/","title":{"rendered":"VI edici\u00f3n del Concurso de Ideas Innovadoras del Departamento Cl\u00ednico-Malvarrosa"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;border-width: 0px 0px 0px 0px;border-color:#e2e2e2;border-style:solid;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;padding: 0px 0px 0px 0px;\"><style type=\"text\/css\">@media only screen and (max-width:1532px) {.fusion-title.fusion-title-1{margin-top:10px!important;margin-bottom:15px!important;}}@media only screen and (max-width:640px) {.fusion-title.fusion-title-1{margin-top:10px!important;margin-bottom:10px!important;}}<\/style><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"margin-top:10px;margin-bottom:15px;\"><h4 class=\"title-heading-left\" style=\"margin:0;\"><ul>\n<li>El objetivo de los premios es detectar oportunidades de mejora en la atenci\u00f3n al paciente, impulsar soluciones creativas y reconocer a los profesionales<\/li>\n<li>Puede participar cualquier persona vinculada laboral o estatutariamente a este Departamento de Salud<\/li>\n<li>El plazo de presentaci\u00f3n de solicitudes finaliza el 19 de septiembre<\/li>\n<\/ul><\/h4><\/div><div ><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"margin-bottom:20px;\"><img width=\"1920\" height=\"1080\" title=\"Imagen noticia\" src=\"https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia.jpg\" class=\"img-responsive wp-image-43119\" srcset=\"https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia-200x113.jpg 200w, https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia-400x225.jpg 400w, https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia-600x338.jpg 600w, https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia-800x450.jpg 800w, https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia-1200x675.jpg 1200w, https:\/\/www.incliva.es\/wp-content\/uploads\/2025\/07\/Imagen-noticia.jpg 1920w\" sizes=\"(max-width: 640px) 100vw, 1200px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-1\" style=\"transform:translate3d(0,0,0);\"><p>El Instituto de Investigaci\u00f3n Sanitaria INCLIVA ha convocado, a trav\u00e9s de su Unidad de Apoyo a la Investigaci\u00f3n, la VI edici\u00f3n del Concurso de Ideas Innovadoras del Departamento Cl\u00ednico-Malvarrosa, dirigido a estimular la cultura innovadora del Hospital Cl\u00ednico Universitario de Val\u00e8ncia y su Departamento.<\/p>\n<p>El objetivo de los premios es detectar oportunidades de mejora en la atenci\u00f3n al paciente, impulsar soluciones creativas y reconocer a los profesionales que participen activamente.<\/p>\n<p>La actual convocatoria establece tres categor\u00edas de premios -incorporando a la Categor\u00eda General y la Categor\u00eda Atenci\u00f3n Primaria, la Categor\u00eda de Enfermer\u00eda- y un m\u00e1ximo de cinco premios.<\/p>\n<p>La Categor\u00eda General, financiada con fondos de la instituci\u00f3n, se dirige a ideas cuya aplicaci\u00f3n sea en cualquier \u00e1rea o servicio del Departamento de Salud Cl\u00ednico-Malvarrosa. Incluye un primer premio, de 4.000 euros, y un segundo premio, de 2.000 euros.<\/p>\n<p>La Categor\u00eda de Enfermer\u00eda, financiada tambi\u00e9n por INCLIVA, se refiere a ideas innovadoras en este \u00e1mbito y a personal de enfermer\u00eda del Departamento de Salud Cl\u00ednico-Malvarrosa. Contempla un premio de 3.000 euros.<\/p>\n<p>La Categor\u00eda de Atenci\u00f3n Primaria, patrocinada por Daiichi-Sankyo, se dirige a ideas sobre el abordaje de la adherencia e inercia terap\u00e9uticas en la gesti\u00f3n de la enfermedad cardiovascular en Atenci\u00f3n Primaria y cuyo participante pertenezca a Atenci\u00f3n Primaria. En esta categor\u00eda hay un primer premio, de 3.000 euros, y un segundo premio, de 2.000 euros.<\/p>\n<p>Los criterios de evaluaci\u00f3n son la novedad de la idea; la repercusi\u00f3n del problema a resolver; el impacto de la soluci\u00f3n propuesta; y la viabilidad.<\/p>\n<p>Podr\u00e1 participar en la convocatoria cualquier persona vinculada laboral o estatutariamente al Departamento de Salud Cl\u00ednico-Malvarrosa. No existe l\u00edmite de solicitudes por participante. Para participar es necesario cumplimentar el formulario habilitado en la p\u00e1gina web (<a href=\"https:\/\/www.incliva.es\/vi-concurso-de-ideas-innovadoras-del-departamento-de-salud-clinico-malvarrosa\/\">https:\/\/www.incliva.es\/vi-concurso-de-ideas-innovadoras-del-departamento-de-salud-clinico-malvarrosa\/<\/a>).<\/p>\n<p>El plazo de presentaci\u00f3n de solicitudes estar\u00e1 abierto hasta el 19 de septiembre de 2025. No se admitir\u00e1n candidaturas recibidas fuera de ese plazo.<\/p>\n<\/div><\/div><\/div><style type=\"text\/css\">.fusion-body .fusion-builder-column-0{width:100% !important;margin-top : 0px;margin-bottom : 0px;}.fusion-builder-column-0 > .fusion-column-wrapper {padding-top : 0px !important;padding-right : 0px !important;margin-right : 1.92%;padding-bottom : 0px !important;padding-left : 0px !important;margin-left : 1.92%;}@media only screen and (max-width:1532px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}@media only screen and (max-width:640px) {.fusion-body .fusion-builder-column-0{width:100% !important;}.fusion-builder-column-0 > .fusion-column-wrapper {margin-right : 1.92%;margin-left : 1.92%;}}<\/style><\/div><style type=\"text\/css\">.fusion-body .fusion-flex-container.fusion-builder-row-1{ padding-top : 0px;margin-top : 0px;padding-right : 0px;padding-bottom : 0px;margin-bottom : 0px;padding-left : 0px;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":43119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[189],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/posts\/43118"}],"collection":[{"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/comments?post=43118"}],"version-history":[{"count":5,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/posts\/43118\/revisions"}],"predecessor-version":[{"id":43163,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/posts\/43118\/revisions\/43163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/media\/43119"}],"wp:attachment":[{"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/media?parent=43118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/categories?post=43118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.incliva.es\/en\/wp-json\/wp\/v2\/tags?post=43118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}